{"id":1381,"date":"2023-09-29T14:36:03","date_gmt":"2023-09-29T12:36:03","guid":{"rendered":"https:\/\/melaniemanuel.fr\/?page_id=1381"},"modified":"2023-10-24T17:14:44","modified_gmt":"2023-10-24T15:14:44","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1381\" class=\"elementor elementor-1381\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b95ac2d e-con-full e-flex e-con e-parent\" data-id=\"5b95ac2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bea3bfe e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"bea3bfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36d1ed39 elementor-widget elementor-widget-heading\" data-id=\"36d1ed39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">ANNECY | au cabinet - \u00e0 domicile - en visio<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ae45773 e-con-full e-flex e-con e-child\" data-id=\"6ae45773\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-332dcc49 elementor-align-end elementor-mobile-align-center elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"332dcc49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/people\/M\u00e9lanie-Manuel-Naturopathe\/pfbid02a1ZnxhqznaCPeJ9d6dpAMPPJzmmNktQoy9KLabD68jFkzfaqKE4ybdq6kjrhgCgwl\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/melaniemanuelnaturopathe\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:0033645644366\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"bca8668a-c1a7-45ca-a09b-aba638241546\" data-name=\"Layer 1\" width=\"14.9685\" height=\"15\" viewBox=\"0 0 14.9685 15\"><path d=\"M14.576,11.0085,12.4827,8.9152a1.3923,1.3923,0,0,0-2.3176.5233,1.4244,1.4244,0,0,1-1.6447.8971A6.455,6.455,0,0,1,4.6328,6.4481,1.3551,1.3551,0,0,1,5.53,4.8033a1.3922,1.3922,0,0,0,.5233-2.3175L3.96.3925a1.4929,1.4929,0,0,0-2.0185,0l-1.42,1.42C-.8994,3.3082.6705,7.27,4.1843,10.7842s7.476,5.1585,8.9712,3.6633L14.576,13.027A1.4931,1.4931,0,0,0,14.576,11.0085Z\" transform=\"translate(0 0)\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">06 45 64 43 66<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a5bed0e e-con-full e-flex e-con e-parent\" data-id=\"1a5bed0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:1}},&quot;sticky&quot;:&quot;top&quot;,&quot;background_motion_fx_range&quot;:&quot;page&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf3334 elementor-widget__width-initial elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"3bf3334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/melaniemanuel.fr\">\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"50\" data-src=\"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/08\/logo-1.png\" class=\"attachment-medium size-medium wp-image-57 lazyload\" alt=\"\" data-srcset=\"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/08\/logo-1-300x50.png 300w, https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/08\/logo-1-768x127.png 768w, https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/08\/logo-1.png 851w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/50;\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f127f01 elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-nav-menu__align-end elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"1f127f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-1f127f01\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1258\"><a aria-expanded=\"false\" href=\"#naturopathie\" class=\"elementor-item elementor-item-anchor menu-link\">Naturopathie<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Menu Toggle\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1259\"><a href=\"#fleurs-de-bach\" class=\"elementor-sub-item elementor-item-anchor menu-link\">Fleurs de Bach<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-209\"><a href=\"#mes-services\" class=\"elementor-item elementor-item-anchor menu-link\">Mes services<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-207\"><a href=\"#mon-approche\" class=\"elementor-item elementor-item-anchor menu-link\">Mon approche<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-206\"><a href=\"#mes-formations\" class=\"elementor-item elementor-item-anchor menu-link\">Mes formations<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-205\"><a href=\"#qui-suis-je\" class=\"elementor-item elementor-item-anchor menu-link\">Qui suis je ?<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-1f127f01\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1258\"><a aria-expanded=\"false\" href=\"#naturopathie\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Naturopathie<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Menu Toggle\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1259\"><a href=\"#fleurs-de-bach\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\">Fleurs de Bach<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-209\"><a href=\"#mes-services\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Mes services<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-207\"><a href=\"#mon-approche\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Mon approche<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-206\"><a href=\"#mes-formations\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Mes formations<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-205\"><a href=\"#qui-suis-je\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Qui suis je ?<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-264dfc53 e-con-full e-flex e-con e-parent\" data-id=\"264dfc53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:924,&quot;url&quot;:&quot;http:\\\/\\\/melaniemanuel.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AdobeStock_133536562-scaled.jpeg&quot;}],&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21d2ae84 e-flex e-con-boxed e-con e-child\" data-id=\"21d2ae84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f98d384 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1f98d384\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mentions l\u00e9gales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d481698 e-flex e-con-boxed e-con e-parent\" data-id=\"7d481698\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2adbf7dc elementor-widget elementor-widget-spacer\" data-id=\"2adbf7dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a2aeff2 elementor-widget elementor-widget-text-editor\" data-id=\"7a2aeff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l\u2019\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : <a href=\"https:\/\/melaniemanuel.fr\">M\u00e9lanie Manuel<\/a> les informations suivantes :<\/p><p><strong>Propri\u00e9taire et \u00e9diteur du site<\/strong><\/p><p>M\u00e9lanie Manuel<\/p><p>3 rue Lieutenant Morel 74960 Meythet &#8211;\u00a0France<\/p><p>SIRET : 949 418 610 00018 \u2013 APE : 96.0909Z<\/p><p><span style=\"font-size: 16px;\">Responsable l\u00e9gal :\u00a0M\u00e9lanie Manuel &#8211;\u00a0<\/span><a style=\"font-size: 16px;\" href=\"mailto:naturo@melaniemanuel.fr\">M\u2019\u00e9crire par email<\/a><span style=\"font-size: 16px;\"> \u2013 06 45 64 43 66<\/span><\/p><p>Responsable publication : M\u00e9lanie Manuel<\/p><p>Graphisme et Web Design :\u00a0DAMARA<\/p><p>H\u00e9bergement :\u00a0Hostinger<\/p><p>Cr\u00e9dit photo :\u00a0Adobe Stock<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8aef1ea e-flex e-con-boxed e-con e-parent\" data-id=\"8aef1ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5668519 elementor-widget elementor-widget-spacer\" data-id=\"5668519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f93d52a e-con-full e-flex e-con e-parent\" data-id=\"3f93d52a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6e179133 e-flex e-con-boxed e-con e-child\" data-id=\"6e179133\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1eee600d e-flex e-con-boxed e-con e-child\" data-id=\"1eee600d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-531427b elementor-widget elementor-widget-spacer\" data-id=\"531427b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc07d94 elementor-widget elementor-widget-accordion\" data-id=\"5cc07d94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"far fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Description des services fournis<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1551\"><p>Le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> \u00a0a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de la soci\u00e9t\u00e9. Le propri\u00e9taire du site s\u2019efforce de fournir sur le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenue responsable des omissions, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. Tous les informations propos\u00e9es sur le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> sont donn\u00e9es \u00e0 titre indicatif, sont non exhaustives, et sont susceptibles d\u2019\u00e9voluer. Elles sont donn\u00e9es sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1552\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1552\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"far fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Propri\u00e9t\u00e9 intellectuelle et contrefa\u00e7ons<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1552\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1552\"><p>Le propri\u00e9taire du site est propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle ou d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site, notamment les textes, images, graphismes, logo, ic\u00f4nes, sons, logiciels\u2026 Toute reproduction, repr\u00e9sentation, modification, publication, adaptation totale ou partielle des \u00e9l\u00e9ments du site, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite, sauf autorisation \u00e9crite pr\u00e9alable \u00e0 l\u2019email : <a href=\"mailto:naturo@melaniemanuel.fr\">naturo@melaniemanuel.fr<\/a> . Toute exploitation non autoris\u00e9e du site ou de l\u2019un quelconque de ces \u00e9l\u00e9ments qu\u2019il contient sera consid\u00e9r\u00e9e comme constitutive d\u2019une contrefa\u00e7on et poursuivie conform\u00e9ment aux dispositions des articles L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1553\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1553\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"far fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Liens hypertextes et cookies<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1553\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1553\"><p>Le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> contient un certain nombre de liens hypertextes vers d\u2019autres sites (partenaires, informations \u2026) mis en place avec l\u2019autorisation de le propri\u00e9taire du site . Cependant, le propri\u00e9taire du site n\u2019a pas la possibilit\u00e9 de v\u00e9rifier le contenu des sites ainsi visit\u00e9s et d\u00e9cline donc toute responsabilit\u00e9 de ce fait quand aux risques \u00e9ventuels de contenus illicites. L\u2019utilisateur est inform\u00e9 que lors de ses visites sur le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>, un ou des cookies sont susceptible de s\u2019installer automatiquement sur son ordinateur. Un cookie est un fichier de petite taille, qui ne permet pas l\u2019identification de l\u2019utilisateur, mais qui enregistre des informations relatives \u00e0 la navigation d\u2019un ordinateur sur un site. Les donn\u00e9es ainsi obtenues visent \u00e0 faciliter la navigation ult\u00e9rieure sur le site, et ont \u00e9galement vocation \u00e0 permettre diverses mesures de fr\u00e9quentation. Le param\u00e9trage du logiciel de navigation permet d\u2019informer de la pr\u00e9sence de cookie et \u00e9ventuellement, de refuser de la mani\u00e8re d\u00e9crite \u00e0 l\u2019adresse suivante : www.cnil.fr Le refus d\u2019installation d\u2019un cookie peut entra\u00eener l\u2019impossibilit\u00e9 d\u2019acc\u00e9der \u00e0 certains services. L\u2019utilisateur peut toutefois configurer son ordinateur pour refuser l\u2019installation des cookies<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1554\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1554\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"far fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Protections des biens et des personnes - Gestion des donn\u00e9es personnelles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1554\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1554\"><p>Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9 : <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>.\u00a0<\/p><p>En France, les donn\u00e9es personnelles sont notamment prot\u00e9g\u00e9es par la loi n\u00b0 78-87 du 6 janvier 1978, la loi n\u00b0 2004-801 du 6 ao\u00fbt 2004, l\u2019article L. 226-13 du Code p\u00e9nal et la Directive Europ\u00e9enne du 24 octobre 1995. Sur le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>, le proprietaire du site ne collecte des informations personnelles relatives \u00e0 l\u2019utilisateur que pour le besoin de certains services propos\u00e9s par le site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>.<\/p><p>L\u2019utilisateur fournit ces informations en toute connaissance de cause, notamment lorsqu\u2019il proc\u00e8de par lui-m\u00eame \u00e0 leur saisie. Il est alors pr\u00e9cis\u00e9 \u00e0 l\u2019utilisateur du site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>\u00a0l\u2019obligation ou non de fournir ces informations.<\/p><p>Conform\u00e9ment aux dispositions des articles 38 et suivants de la loi 78-17 du 6 janvier 1978 relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s, tout utilisateur dispose d\u2019un droit d\u2019acc\u00e8s, de rectification, de suppression et d\u2019opposition aux donn\u00e9es personnelles le concernant. Pour l\u2019exercer, adressez votre demande \u00e0 <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> par email : <a href=\"mailto:naturo@melaniemanuel.fr\">naturo@melaniemanuel.fr<\/a> ou en effectuant sa demande \u00e9crite et sign\u00e9e, accompagn\u00e9e d\u2019une copie du titre d\u2019identit\u00e9 avec signature du titulaire de la pi\u00e8ce, en pr\u00e9cisant l\u2019adresse \u00e0 laquelle la r\u00e9ponse doit \u00eatre envoy\u00e9e. Aucune information personnelle de l\u2019utilisateur du site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> n\u2019est publi\u00e9e \u00e0 l\u2019insu de l\u2019utilisateur, \u00e9chang\u00e9e, transf\u00e9r\u00e9e, c\u00e9d\u00e9e ou vendue sur un support quelconque \u00e0 des tiers. Seule l\u2019hypoth\u00e8se du rachat du site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a> \u00e0 le proprietaire du site et de ses droits permettrait la transmission des dites informations \u00e0 l\u2019\u00e9ventuel acqu\u00e9reur qui serait \u00e0 son tour tenu de la m\u00eame obligation de conservation et de modification des donn\u00e9es vis \u00e0 vis de l\u2019utilisateur du site <a href=\"https:\/\/melaniemanuel.fr\/\">melaniemanuel.fr<\/a>. Les bases de donn\u00e9es sont prot\u00e9g\u00e9es par les dispositions de la loi du 1er juillet 1998 transposant la directive 96\/9 du 11 mars 1996 relative \u00e0 la protection juridique des bases de donn\u00e9es. Les mentions l\u00e9gales ont \u00e9t\u00e9s g\u00e9n\u00e9r\u00e9es par mentions l\u00e9gales<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f82ab7 e-flex e-con-boxed e-con e-parent\" data-id=\"7f82ab7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc2fb4 elementor-widget elementor-widget-spacer\" data-id=\"2bc2fb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-367280b6 e-flex e-con-boxed e-con e-parent\" data-id=\"367280b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-265327cc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"265327cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50fb20de elementor-widget elementor-widget-spacer\" data-id=\"50fb20de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2022287a e-con-full e-flex e-con e-child\" data-id=\"2022287a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-136b719d e-con-full e-flex e-con e-child\" data-id=\"136b719d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a90b567 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"3a90b567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a47d254 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6a47d254\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">06 45 64 43 66<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">naturo@melaniemanuel.fr<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd0759f e-con-full e-flex e-con e-child\" data-id=\"cd0759f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-234f55b7 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"234f55b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Annecy<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb513c1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3bb513c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> au cabinet <br> \u00e0 domicile <br> en visio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29225a58 e-con-full e-flex e-con e-child\" data-id=\"29225a58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46a5c08f elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"46a5c08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La Maison Ga\u00efa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d961fca elementor-widget elementor-widget-text-editor\" data-id=\"3d961fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t31 Route de Frangy <br> 74960 Annecy\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1311af e-transform elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b1311af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lamaisongaia.fr\/consultations-individuelles\/melanie-manuel\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prendre rendez-vous<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f23295 e-grid-align-right e-grid-align-tablet-left elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"66f23295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-be32a58\" href=\"https:\/\/www.facebook.com\/people\/M\u00e9lanie-Manuel-Naturopathe\/pfbid02a1ZnxhqznaCPeJ9d6dpAMPPJzmmNktQoy9KLabD68jFkzfaqKE4ybdq6kjrhgCgwl\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-animation-grow elementor-repeater-item-af5d7dd\" href=\"https:\/\/www.instagram.com\/melaniemanuelnaturopathe\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e957479 elementor-widget elementor-widget-spacer\" data-id=\"2e957479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-556cd13a e-con-full e-flex e-con e-parent\" data-id=\"556cd13a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2eaf509b e-con-full e-flex e-con e-child\" data-id=\"2eaf509b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebdc88f elementor-widget elementor-widget-heading\" data-id=\"ebdc88f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00a9 M\u00e9lanie Manuel -  2026 - Tous droits r\u00e9serv\u00e9s<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff46214 elementor-widget elementor-widget-text-editor\" data-id=\"1ff46214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>_<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62205072 elementor-widget elementor-widget-heading\" data-id=\"62205072\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Design : Damara<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7dc44009 e-flex e-con-boxed e-con e-child\" data-id=\"7dc44009\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51ed372 e-transform e-transform elementor-widget elementor-widget-heading\" data-id=\"51ed372\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-2,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/\">Mentions l\u00e9gales<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47c1f4a2 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"47c1f4a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7330ceb0 e-transform e-transform elementor-widget elementor-widget-heading\" data-id=\"7330ceb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-2,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/melaniemanuel.fr\/index.php\/cookies\/\">Politique des cookies<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15361679 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"15361679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce8dc92 e-transform e-transform elementor-widget elementor-widget-heading\" data-id=\"5ce8dc92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-2,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/melaniemanuel.fr\/index.php\/politique-de-confidentialite\/\">Politique de confidentialit\u00e9<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ANNECY | au cabinet &#8211; \u00e0 domicile &#8211; en visio 06 45 64 43 66 Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l\u2019\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : M\u00e9lanie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1381","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"-\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mentions l\u00e9gales -\" \/>\n\t\t<meta property=\"og:description\" content=\"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1516\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2021\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-29T12:36:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-24T15:14:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/M\u00e9lanie-Manuel-Naturopathe\/pfbid02a1ZnxhqznaCPeJ9d6dpAMPPJzmmNktQoy9KLabD68jFkzfaqKE4ybdq6kjrhgCgwl\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mentions l\u00e9gales -\" \/>\n\t\t<meta name=\"twitter:description\" content=\"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/melaniemanuel.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/#listItem\",\"name\":\"Mentions l\\u00e9gales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/#listItem\",\"position\":2,\"name\":\"Mentions l\\u00e9gales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/#webpage\",\"url\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/\",\"name\":\"Mentions l\\u00e9gales -\",\"description\":\"ANNECY | au cabinet - \\u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\\u00e9gales Conform\\u00e9ment aux dispositions des articles 6-III et 19 de la\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/index.php\\\/mentions-legales\\\/#breadcrumblist\"},\"datePublished\":\"2023-09-29T14:36:03+02:00\",\"dateModified\":\"2023-10-24T17:14:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/#website\",\"url\":\"https:\\\/\\\/melaniemanuel.fr\\\/\",\"name\":\"melaniemanuel.fr\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/melaniemanuel.fr\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mentions l\u00e9gales -","description":"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la","canonical_url":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/melaniemanuel.fr#listItem","position":1,"name":"Home","item":"https:\/\/melaniemanuel.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/#listItem","name":"Mentions l\u00e9gales"}},{"@type":"ListItem","@id":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/#listItem","position":2,"name":"Mentions l\u00e9gales","previousItem":{"@type":"ListItem","@id":"https:\/\/melaniemanuel.fr#listItem","name":"Home"}}]},{"@type":"WebPage","@id":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/#webpage","url":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/","name":"Mentions l\u00e9gales -","description":"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/melaniemanuel.fr\/#website"},"breadcrumb":{"@id":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/#breadcrumblist"},"datePublished":"2023-09-29T14:36:03+02:00","dateModified":"2023-10-24T17:14:44+02:00"},{"@type":"WebSite","@id":"https:\/\/melaniemanuel.fr\/#website","url":"https:\/\/melaniemanuel.fr\/","name":"melaniemanuel.fr","inLanguage":"en-US","publisher":{"@id":"https:\/\/melaniemanuel.fr\/#person"}}]},"og:locale":"en_US","og:site_name":"-","og:type":"article","og:title":"Mentions l\u00e9gales -","og:description":"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la","og:url":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/","og:image":"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg","og:image:secure_url":"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg","og:image:width":1516,"og:image:height":2021,"article:published_time":"2023-09-29T12:36:03+00:00","article:modified_time":"2023-10-24T15:14:44+00:00","article:publisher":"https:\/\/www.facebook.com\/people\/M\u00e9lanie-Manuel-Naturopathe\/pfbid02a1ZnxhqznaCPeJ9d6dpAMPPJzmmNktQoy9KLabD68jFkzfaqKE4ybdq6kjrhgCgwl\/","twitter:card":"summary_large_image","twitter:title":"Mentions l\u00e9gales -","twitter:description":"ANNECY | au cabinet - \u00e0 domicile - en visio 06 45 64 43 66 Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Naturopathie Fleurs de Bach Mes services Mon approche Mes formations Qui suis je ? Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la","twitter:image":"https:\/\/melaniemanuel.fr\/wp-content\/uploads\/2023\/09\/photo-melanie-manuel.jpg"},"aioseo_meta_data":{"post_id":"1381","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-29 13:01:06","updated":"2025-06-04 15:22:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/melaniemanuel.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMentions l\u00e9gales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/melaniemanuel.fr"},{"label":"Mentions l\u00e9gales","link":"https:\/\/melaniemanuel.fr\/index.php\/mentions-legales\/"}],"_links":{"self":[{"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/pages\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":65,"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/pages\/1381\/revisions"}],"predecessor-version":[{"id":1815,"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/pages\/1381\/revisions\/1815"}],"wp:attachment":[{"href":"https:\/\/melaniemanuel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}